{"id":283216,"date":"2026-07-15T01:59:30","date_gmt":"2026-07-15T07:59:30","guid":{"rendered":"https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/"},"modified":"2026-07-15T01:59:30","modified_gmt":"2026-07-15T07:59:30","slug":"lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex","status":"publish","type":"product","link":"https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/","title":{"rendered":"Lexmark 25b0610 Multifuncional  Mx826ade, Np , Ppm 70 Negro, Laser Monocromatico, Usb, Ethernet, Duplex"},"content":{"rendered":"<table class=\"descripcion\">\n<tr>\n<td>Nmero de parte<\/td>\n<\/tr>\n<tr>\n<td>25b0610<\/td>\n<\/tr>\n<tr>\n<td>Tecnologa de impresin<\/td>\n<\/tr>\n<tr>\n<td>Lser monocromtico<\/td>\n<\/tr>\n<tr>\n<td>Funcin<\/td>\n<\/tr>\n<tr>\n<td>Escaneo en color<\/td>\n<\/tr>\n<tr>\n<td>Proceso de copiar<\/td>\n<\/tr>\n<tr>\n<td>Envo de fax<\/td>\n<\/tr>\n<tr>\n<td>Escaneo de red<\/td>\n<\/tr>\n<tr>\n<td>Impresin<\/td>\n<\/tr>\n<tr>\n<td>Tamao del grupo de trabajo<\/td>\n<\/tr>\n<tr>\n<td>Grupo de trabajo grande<\/td>\n<\/tr>\n<tr>\n<td>Pantalla tctil<\/td>\n<\/tr>\n<tr>\n<td>S<\/td>\n<\/tr>\n<tr>\n<td>Pantalla<\/td>\n<\/tr>\n<tr>\n<td>Pantalla tctil en color e-task de 10 pulgadas 25 cm de lexmark<\/td>\n<\/tr>\n<tr>\n<td>Velocidad de impresin carta, negro<\/td>\n<\/tr>\n<tr>\n<td>Hasta 70 ppm6<\/td>\n<\/tr>\n<tr>\n<td>Velocidad de impresin carta, negro duplex<\/td>\n<\/tr>\n<tr>\n<td>Hasta 42 spm6<\/td>\n<\/tr>\n<tr>\n<td>Velocidad de impresin a4, negro<\/td>\n<\/tr>\n<tr>\n<td>Hasta 66 ppm6<\/td>\n<\/tr>\n<tr>\n<td>Velocidad de impresin a4, negro duplex<\/td>\n<\/tr>\n<tr>\n<td>Hasta 40 spm6<\/td>\n<\/tr>\n<tr>\n<td>Tiempo de salida de la primera pgina negro tan rpido como<\/td>\n<\/tr>\n<tr>\n<td>Tan solo 4.0 segundos<\/td>\n<\/tr>\n<tr>\n<td>Impresin dplex 2 caras<\/td>\n<\/tr>\n<tr>\n<td>Dplex integrado<\/td>\n<\/tr>\n<tr>\n<td>Resolucin de impresin, negro<\/td>\n<\/tr>\n<tr>\n<td>Calidad de imagen 1200<\/td>\n<\/tr>\n<tr>\n<td>1200 x 1200 dpi<\/td>\n<\/tr>\n<tr>\n<td>Calidad de imagen 2400<\/td>\n<\/tr>\n<tr>\n<td>300 x 300 dpi<\/td>\n<\/tr>\n<tr>\n<td>600 x 600 dpi<\/td>\n<\/tr>\n<tr>\n<td>Velocidad de copiado carta, negro<\/td>\n<\/tr>\n<tr>\n<td>Hasta 70 cpm6<\/td>\n<\/tr>\n<tr>\n<td>Velocidad de copiado carta, negro duplex<\/td>\n<\/tr>\n<tr>\n<td>Hasta 44 spm6<\/td>\n<\/tr>\n<tr>\n<td>Velocidad de copiado a4, color<\/td>\n<\/tr>\n<tr>\n<td>Hasta 66 cpm6<\/td>\n<\/tr>\n<tr>\n<td>Velocidad de copiado a4, negro duplex<\/td>\n<\/tr>\n<tr>\n<td>Hasta 42 spm6<\/td>\n<\/tr>\n<tr>\n<td>Tiempo de salida de la primera copia negro tan rpido como<\/td>\n<\/tr>\n<tr>\n<td>Tan solo 4.0 segundos<\/td>\n<\/tr>\n<tr>\n<td>Rango de reduccin \/ ampliacin<\/td>\n<\/tr>\n<tr>\n<td>25 &#8211; 400<\/td>\n<\/tr>\n<tr>\n<td>A4 \/ carta simplex velocidad de digitalizacin escaneado negro<\/td>\n<\/tr>\n<tr>\n<td>Hasta 72 \/ 75 lados por minuto<\/td>\n<\/tr>\n<tr>\n<td>A4 \/ carta simplex velocidad de digitalizacin escaneado color<\/td>\n<\/tr>\n<tr>\n<td>Hasta 72 \/ 75 lados por minuto<\/td>\n<\/tr>\n<tr>\n<td>A4 \/ carta velocidad de digitalizacin escaneado dplex negro<\/td>\n<\/tr>\n<tr>\n<td>Hasta 144 \/ 150 lados por minuto<\/td>\n<\/tr>\n<tr>\n<td>A4 \/ carta velocidad de digitalizacin escaneado dplex color<\/td>\n<\/tr>\n<tr>\n<td>Hasta 144 \/ 150 lados por minuto<\/td>\n<\/tr>\n<tr>\n<td>\u00e1rea de digitalizacin escaneado, mxima en mm<\/td>\n<\/tr>\n<tr>\n<td>215.9 x 355.6 mm<\/td>\n<\/tr>\n<tr>\n<td>Digitalizacin desde el alimentador automtico de documentos<\/td>\n<\/tr>\n<tr>\n<td>Dadf dplex de un solo paso<\/td>\n<\/tr>\n<tr>\n<td>Tipo de escaner<\/td>\n<\/tr>\n<tr>\n<td>Escner plano con adf<\/td>\n<\/tr>\n<tr>\n<td>Tecnologa de digitalizacin escaneado<\/td>\n<\/tr>\n<tr>\n<td>Ccd<\/td>\n<\/tr>\n<tr>\n<td>Resolucin ptica de digitalizacin escaneado<\/td>\n<\/tr>\n<tr>\n<td>600 x 600 ppi negro<\/td>\n<\/tr>\n<tr>\n<td>Up to 600 x 600 ppi color<\/td>\n<\/tr>\n<tr>\n<td>Formatos de archivos de digitalizacin enviar como<\/td>\n<\/tr>\n<tr>\n<td>Jpeg, jpg<\/td>\n<\/tr>\n<tr>\n<td>Pdf<\/td>\n<\/tr>\n<tr>\n<td>Pdf seguro<\/td>\n<\/tr>\n<tr>\n<td>Tiff<\/td>\n<\/tr>\n<tr>\n<td>Xps<\/td>\n<\/tr>\n<tr>\n<td>Archivo pdf a-1a, a-1b<\/td>\n<\/tr>\n<tr>\n<td>Pdf con capacidad de bsqueda<\/td>\n<\/tr>\n<tr>\n<td>Destinos de digitalizacin<\/td>\n<\/tr>\n<tr>\n<td>E-mail<\/td>\n<\/tr>\n<tr>\n<td>Ftp<\/td>\n<\/tr>\n<tr>\n<td>Memoria usb<\/td>\n<\/tr>\n<tr>\n<td>Usb o computadora conectada a la red<\/td>\n<\/tr>\n<tr>\n<td>Lexmark document solutions suite ldss<\/td>\n<\/tr>\n<tr>\n<td>Velocidad del mdem<\/td>\n<\/tr>\n<tr>\n<td>Max is 33,600 bps, v.34 half-duplex kbps<\/td>\n<\/tr>\n<tr>\n<td>Velocidad de transmisin de fax<\/td>\n<\/tr>\n<tr>\n<td> 3 segundos por pgina<\/td>\n<\/tr>\n<tr>\n<td>Procesador<\/td>\n<\/tr>\n<tr>\n<td>Quad core, 1200 mhz<\/td>\n<\/tr>\n<tr>\n<td>Memoria, estndar<\/td>\n<\/tr>\n<tr>\n<td>2048 mb<\/td>\n<\/tr>\n<tr>\n<td>Memoria, mxima<\/td>\n<\/tr>\n<tr>\n<td>6144 mb<\/td>\n<\/tr>\n<tr>\n<td>Disco duro<\/td>\n<\/tr>\n<tr>\n<td>Incluido en la configuracin<\/td>\n<\/tr>\n<tr>\n<td>Sistemas operativos apple soportados<\/td>\n<\/tr>\n<tr>\n<td>Apple os x 10.6, 10.7, 10.8, 10.9, 10.10, 10.11, 10.12, 10.13<\/td>\n<\/tr>\n<tr>\n<td>Sistemas operativos linux soportados<\/td>\n<\/tr>\n<tr>\n<td>Debian gnu\/linux 7.0, 8.0<\/td>\n<\/tr>\n<tr>\n<td>Suse linux enterprise server 10, 11, 12<\/td>\n<\/tr>\n<tr>\n<td>Ubuntu 12.04 lts, 14.04 lts, 15.04<\/td>\n<\/tr>\n<tr>\n<td>Opensuse linux 13.2<\/td>\n<\/tr>\n<tr>\n<td>Ubuntu 16.04 lts<\/td>\n<\/tr>\n<tr>\n<td>Fedora 23, 24<\/td>\n<\/tr>\n<tr>\n<td>Red hat enterprise linux ws 6, 7<\/td>\n<\/tr>\n<tr>\n<td>Opensuse linux 42.3<\/td>\n<\/tr>\n<tr>\n<td>Soporta los sistemas operativos microsoft windows<\/td>\n<\/tr>\n<tr>\n<td>Windows server 2003<\/td>\n<\/tr>\n<tr>\n<td>Windows server 2003 x64<\/td>\n<\/tr>\n<tr>\n<td>Windows vista<\/td>\n<\/tr>\n<tr>\n<td>Windows vista x64<\/td>\n<\/tr>\n<tr>\n<td>Windows server 2008<\/td>\n<\/tr>\n<tr>\n<td>Windows server 2008 x64<\/td>\n<\/tr>\n<tr>\n<td>Windows 7<\/td>\n<\/tr>\n<tr>\n<td>Windows 7 x64<\/td>\n<\/tr>\n<tr>\n<td>Windows server 2008 r2<\/td>\n<\/tr>\n<tr>\n<td>Windows 8<\/td>\n<\/tr>\n<tr>\n<td>Windows 8 x64<\/td>\n<\/tr>\n<tr>\n<td>Windows server 2012<\/td>\n<\/tr>\n<tr>\n<td>Windows 8.1<\/td>\n<\/tr>\n<tr>\n<td>Windows 8.1 x64<\/td>\n<\/tr>\n<tr>\n<td>Windows server 2012 r2<\/td>\n<\/tr>\n<tr>\n<td>Windows rt<\/td>\n<\/tr>\n<tr>\n<td>Windows rt 8.1<\/td>\n<\/tr>\n<tr>\n<td>Windows 10<\/td>\n<\/tr>\n<tr>\n<td>Sistemas operativos unix soportados<\/td>\n<\/tr>\n<tr>\n<td>Sun solaris x86 10, 11<\/td>\n<\/tr>\n<tr>\n<td>Sun solaris sparc 10, 11<\/td>\n<\/tr>\n<tr>\n<td>Ibm aix 6.1, 7.1<\/td>\n<\/tr>\n<tr>\n<td>Administracin del papel estndar<\/td>\n<\/tr>\n<tr>\n<td>Entrada de 550 hojas<\/td>\n<\/tr>\n<tr>\n<td>Alimentador multipropsito de 100 hojas<\/td>\n<\/tr>\n<tr>\n<td>Bandeja de salida de 550 hojas<\/td>\n<\/tr>\n<tr>\n<td>Duplex integrado<\/td>\n<\/tr>\n<tr>\n<td>Bandeja de 550 hojas<\/td>\n<\/tr>\n<tr>\n<td>Administracin del papel opcional<\/td>\n<\/tr>\n<tr>\n<td>Bandeja de 550 hojas<\/td>\n<\/tr>\n<tr>\n<td>Buzn de 4 bandejas<\/td>\n<\/tr>\n<tr>\n<td>Apilador offset<\/td>\n<\/tr>\n<tr>\n<td>Acabadora de grapas<\/td>\n<\/tr>\n<tr>\n<td>Staple punch finisher<\/td>\n<\/tr>\n<tr>\n<td>Bandeja de 2100 hojas debe eliminar 1 bandeja de 550 hojas<\/td>\n<\/tr>\n<tr>\n<td>Capacidad de entrada de papel, estndar<\/td>\n<\/tr>\n<tr>\n<td>Hasta 1200 hojas bond de 20 lb o 75 g\/m2<\/td>\n<\/tr>\n<tr>\n<td>Capacidad de entrada de papel, mxima<\/td>\n<\/tr>\n<tr>\n<td>Hasta 2300 hojas bond de 20 lb o 75 g\/m2<\/td>\n<\/tr>\n<tr>\n<td>Capacidad de salida de papel, estndar<\/td>\n<\/tr>\n<tr>\n<td>Hasta 550 hojas bond de 20 lb o 75 g\/m2<\/td>\n<\/tr>\n<tr>\n<td>Capacidad de salida de papel, mxima<\/td>\n<\/tr>\n<tr>\n<td>Hasta 1050 hojas bond de 20 lb o 75 g\/m2<\/td>\n<\/tr>\n<tr>\n<td>Rango de peso del papel soportado &#8211; bandeja estndar g\/m2<\/td>\n<\/tr>\n<tr>\n<td>60 &#8211; 176 gsm<\/td>\n<\/tr>\n<tr>\n<td>Integrated tray card stock upper limit grain short<\/td>\n<\/tr>\n<tr>\n<td>Cubierta &#8211; 176 gsm 65 lb<\/td>\n<\/tr>\n<tr>\n<td>Ndice bristol &#8211; 199 gsm 110 lb<\/td>\n<\/tr>\n<tr>\n<td>Etiqueta &#8211; 203 gsm 125 lb<\/td>\n<\/tr>\n<tr>\n<td>Adf<\/td>\n<\/tr>\n<tr>\n<td>Alimentador automtico de documentos de 200 hojas<\/td>\n<\/tr>\n<tr>\n<td>Capacidad de entrada de papel para copiadora\/fax\/escner adf<\/td>\n<\/tr>\n<tr>\n<td>Hasta 200 hojas bond de 20 lb o 75 g\/m2<\/td>\n<\/tr>\n<tr>\n<td>Capacidad de salida de papel para copiadora\/fax\/escner adf<\/td>\n<\/tr>\n<tr>\n<td>Hasta 200 hojas bond de 20 lb o 75 g\/m2<\/td>\n<\/tr>\n<tr>\n<td>Opcin de acabado<\/td>\n<\/tr>\n<tr>\n<td>S<\/td>\n<\/tr>\n<tr>\n<td>Nmero de entradas de papel, estndar<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<\/tr>\n<tr>\n<td>Nmero de entradas de papel, mximo<\/td>\n<\/tr>\n<tr>\n<td>5<\/td>\n<\/tr>\n<tr>\n<td>Tipos de papel soportados<\/td>\n<\/tr>\n<tr>\n<td>Cartulina<\/td>\n<\/tr>\n<tr>\n<td>Etiquetas web dobles<\/td>\n<\/tr>\n<tr>\n<td>Sobres<\/td>\n<\/tr>\n<tr>\n<td>Etiquetas integradas<\/td>\n<\/tr>\n<tr>\n<td>Etiquetas de papel<\/td>\n<\/tr>\n<tr>\n<td>Papel normal<\/td>\n<\/tr>\n<tr>\n<td>Transparencias<\/td>\n<\/tr>\n<tr>\n<td>Consulte la gua de cartulina y etiquetas.<\/td>\n<\/tr>\n<tr>\n<td>Tamaos de papel soportados<\/td>\n<\/tr>\n<tr>\n<td>10 sobre<\/td>\n<\/tr>\n<tr>\n<td>Sobre 7 3\/4<\/td>\n<\/tr>\n<tr>\n<td>9 sobre<\/td>\n<\/tr>\n<tr>\n<td>A4<\/td>\n<\/tr>\n<tr>\n<td>A5<\/td>\n<\/tr>\n<tr>\n<td>Sobre b5<\/td>\n<\/tr>\n<tr>\n<td>Sobre c5<\/td>\n<\/tr>\n<tr>\n<td>Sobre dl<\/td>\n<\/tr>\n<tr>\n<td>Ejecutivo<\/td>\n<\/tr>\n<tr>\n<td>Folio<\/td>\n<\/tr>\n<tr>\n<td>Jis-b5<\/td>\n<\/tr>\n<tr>\n<td>Legal<\/td>\n<\/tr>\n<tr>\n<td>Carta<\/td>\n<\/tr>\n<tr>\n<td>Declaracin<\/td>\n<\/tr>\n<tr>\n<td>Universal<\/td>\n<\/tr>\n<tr>\n<td>Oficio<\/td>\n<\/tr>\n<tr>\n<td>A6<\/td>\n<\/tr>\n<tr>\n<td>Puertos estndar<\/td>\n<\/tr>\n<tr>\n<td>One internal card slot<\/td>\n<\/tr>\n<tr>\n<td>Especificacin usb 2.0 certificacin de alta velocidad tipo b<\/td>\n<\/tr>\n<tr>\n<td>Gigabit ethernet 10\/100\/1000<\/td>\n<\/tr>\n<tr>\n<td>Front usb 2.0 specification hi-speed certified port type a<\/td>\n<\/tr>\n<tr>\n<td>Dos puertos con certificacin hi-speed  and 8203; and 8203;con especificacin usb 2.0 posterior tipo a<\/td>\n<\/tr>\n<tr>\n<td>Puertos locales opcionales<\/td>\n<\/tr>\n<tr>\n<td>Internal rs-232c serial<\/td>\n<\/tr>\n<tr>\n<td>Internal 1284-b bidirectional parallel<\/td>\n<\/tr>\n<tr>\n<td>Puertos de red opcionales<\/td>\n<\/tr>\n<tr>\n<td>Opcin wifi marknet n8370<\/td>\n<\/tr>\n<tr>\n<td>Servidor de impresin ethernet de fibra marknet n8230<\/td>\n<\/tr>\n<tr>\n<td>Opcin wifi marknet n8372<\/td>\n<\/tr>\n<tr>\n<td>Usb directo<\/td>\n<\/tr>\n<tr>\n<td>S<\/td>\n<\/tr>\n<tr>\n<td>Red ethernet<\/td>\n<\/tr>\n<tr>\n<td>S<\/td>\n<\/tr>\n<tr>\n<td>Protocolo de soporte de red<\/td>\n<\/tr>\n<tr>\n<td>Tcp\/ip ipv4<\/td>\n<\/tr>\n<tr>\n<td>Appletalk\u0099<\/td>\n<\/tr>\n<tr>\n<td>Tcp\/ip ipv6<\/td>\n<\/tr>\n<tr>\n<td>Tcp<\/td>\n<\/tr>\n<tr>\n<td>Udp<\/td>\n<\/tr>\n<tr>\n<td>Mtodos de impresin de red<\/td>\n<\/tr>\n<tr>\n<td>Lpr\/lpd<\/td>\n<\/tr>\n<tr>\n<td>Ip directo puerto 9100<\/td>\n<\/tr>\n<tr>\n<td>Ip mejorado puerto 9400<\/td>\n<\/tr>\n<tr>\n<td>Ftp, tftp<\/td>\n<\/tr>\n<tr>\n<td>Thinprint .print integration<\/td>\n<\/tr>\n<tr>\n<td>Telnet<\/td>\n<\/tr>\n<tr>\n<td>Ipp 1.0, 1.1, 2.0 protocolo de impresin de internet<\/td>\n<\/tr>\n<tr>\n<td>Protocolos de gestin de red1<\/td>\n<\/tr>\n<tr>\n<td>Http<\/td>\n<\/tr>\n<tr>\n<td>Https ssl\/tls<\/td>\n<\/tr>\n<tr>\n<td>Snmpv1, snmpv2c<\/td>\n<\/tr>\n<tr>\n<td>Snmpv3<\/td>\n<\/tr>\n<tr>\n<td>Wins<\/td>\n<\/tr>\n<tr>\n<td>Igmp<\/td>\n<\/tr>\n<tr>\n<td>Bootp, rarp<\/td>\n<\/tr>\n<tr>\n<td>Apipa autoip<\/td>\n<\/tr>\n<tr>\n<td>Dhcp<\/td>\n<\/tr>\n<tr>\n<td>Icmp<\/td>\n<\/tr>\n<tr>\n<td>Dns<\/td>\n<\/tr>\n<tr>\n<td>Bonjour<\/td>\n<\/tr>\n<tr>\n<td>Ddns<\/td>\n<\/tr>\n<tr>\n<td>Mdns<\/td>\n<\/tr>\n<tr>\n<td>Arp<\/td>\n<\/tr>\n<tr>\n<td>Ntp<\/td>\n<\/tr>\n<tr>\n<td>Telnet<\/td>\n<\/tr>\n<tr>\n<td>Finger<\/td>\n<\/tr>\n<tr>\n<td>Seguridad de red<\/td>\n<\/tr>\n<tr>\n<td>Snmpv3<\/td>\n<\/tr>\n<tr>\n<td>802.1x authentication: md5, mschapv2, leap, peap, tls, ttls<\/td>\n<\/tr>\n<tr>\n<td>Ipsec<\/td>\n<\/tr>\n<tr>\n<td>Area de impresin mm<\/td>\n<\/tr>\n<tr>\n<td>4.2 mm a partir de los bordes superior, inferior, derecho e izquierdo dentro<\/td>\n<\/tr>\n<tr>\n<td>Lenguajes de impresin estndar<\/td>\n<\/tr>\n<tr>\n<td>Emulacin pcl 5e<\/td>\n<\/tr>\n<tr>\n<td>Emulacin pcl 6<\/td>\n<\/tr>\n<tr>\n<td>Flujo de datos de la impresora personal ppds<\/td>\n<\/tr>\n<tr>\n<td>Emulacin postscript 3<\/td>\n<\/tr>\n<tr>\n<td>Imagen directa<\/td>\n<\/tr>\n<tr>\n<td>Microsoft xps especificacin de papel xml<\/td>\n<\/tr>\n<tr>\n<td>Airprint\u0099<\/td>\n<\/tr>\n<tr>\n<td>Pdf 1.7 emulacin<\/td>\n<\/tr>\n<tr>\n<td>Conjunto de fuentes y smbolos<\/td>\n<\/tr>\n<tr>\n<td>3 de 9 fuentes escalables pcl 5e en estrecha, regular y amplia<\/td>\n<\/tr>\n<tr>\n<td>158 fuentes postscript escalables<\/td>\n<\/tr>\n<tr>\n<td>2 fuentes de mapa de bits pcl<\/td>\n<\/tr>\n<tr>\n<td>39 fuentes ppds escalables<\/td>\n<\/tr>\n<tr>\n<td>5 fuentes de mapa de bits ppds<\/td>\n<\/tr>\n<tr>\n<td>84 fuentes pcl escalables<\/td>\n<\/tr>\n<tr>\n<td>Ocr-a, ocr-b, fuentes pcl 5e escalables<\/td>\n<\/tr>\n<tr>\n<td>Para obtener ms informacin, consulte la referencia tcnica.<\/td>\n<\/tr>\n<tr>\n<td>Rendimiento de cartuchos hasta5<\/td>\n<\/tr>\n<tr>\n<td>Cartucho para 7.500 pginas<\/td>\n<\/tr>\n<tr>\n<td>Cartucho de alto rendimiento para 15.000 pginas<\/td>\n<\/tr>\n<tr>\n<td>Cartucho de rendimiento extra alto para 35.000 pginas<\/td>\n<\/tr>\n<tr>\n<td>Cartucho de ultra alto rendimiento para 55.000 pginas<\/td>\n<\/tr>\n<tr>\n<td>Rendimiento estimado de la unidad de imgenes hasta<\/td>\n<\/tr>\n<tr>\n<td>Hasta 150000 pginas, basado en 3 pginas de media por trabajo en tamao a4\/carta ~ 5 de cobertura4<\/td>\n<\/tr>\n<tr>\n<td>Suministros embarcados con el equipo<\/td>\n<\/tr>\n<tr>\n<td>Cartucho de tner del programa de devolucin de arranque de 11,000 pginas<\/td>\n<\/tr>\n<tr>\n<td>Cartuchos de repuesto:<\/td>\n<\/tr>\n<tr>\n<td>El producto funciona solo con cartuchos de reemplazo diseados para su uso en una regin geogrfica especfica. visita www.lexmark.com\/regions para ms detalles.<\/td>\n<\/tr>\n<tr>\n<td>Tamao con empaque alto x ancho x profundo en mm<\/td>\n<\/tr>\n<tr>\n<td>1365 x 770 x 830 mm<\/td>\n<\/tr>\n<tr>\n<td>Peso con empaque kg<\/td>\n<\/tr>\n<tr>\n<td>94.5 kg<\/td>\n<\/tr>\n<tr>\n<td>Tamao alto x ancho x profundo en mm<\/td>\n<\/tr>\n<tr>\n<td>1150.6 x 685.8 x 693.4 mm<\/td>\n<\/tr>\n<tr>\n<td>Peso<\/td>\n<\/tr>\n<tr>\n<td>67.0 kg<\/td>\n<\/tr>\n<tr>\n<td>Nivel de ruido, inactiva<\/td>\n<\/tr>\n<tr>\n<td>14 dba<\/td>\n<\/tr>\n<tr>\n<td>Nivel de ruido impresin, operando<\/td>\n<\/tr>\n<tr>\n<td>56 dba<\/td>\n<\/tr>\n<tr>\n<td>Nivel de ruido en impresin en modo dplex dos caras, operando<\/td>\n<\/tr>\n<tr>\n<td>55 dba<\/td>\n<\/tr>\n<tr>\n<td>Nivel de ruido copia, operando<\/td>\n<\/tr>\n<tr>\n<td>59 dba<\/td>\n<\/tr>\n<tr>\n<td>Nivel de ruido digitalizacin, operando<\/td>\n<\/tr>\n<tr>\n<td>57 dba<\/td>\n<\/tr>\n<tr>\n<td>Energy star<\/td>\n<\/tr>\n<tr>\n<td>S<\/td>\n<\/tr>\n<tr>\n<td>Promedio de consumo de energa modo de hibernacin<\/td>\n<\/tr>\n<tr>\n<td>0.2 watts<\/td>\n<\/tr>\n<tr>\n<td>Promedio de consumo de energa modo de suspensin<\/td>\n<\/tr>\n<tr>\n<td>3.1 watts<\/td>\n<\/tr>\n<tr>\n<td>Consumo promedio de energa el modo listo<\/td>\n<\/tr>\n<tr>\n<td>50 watts<\/td>\n<\/tr>\n<tr>\n<td>Consumo promedio de energa modo de impresin<\/td>\n<\/tr>\n<tr>\n<td>850 watts<\/td>\n<\/tr>\n<tr>\n<td>Consumo promedio de energa modo de copiado<\/td>\n<\/tr>\n<tr>\n<td>900 watts<\/td>\n<\/tr>\n<tr>\n<td>Consumo promedio de energa modo de escner<\/td>\n<\/tr>\n<tr>\n<td>86 watts<\/td>\n<\/tr>\n<tr>\n<td>Consumo elctrico tpico segn energy star tec<\/td>\n<\/tr>\n<tr>\n<td>3.4 kilowatt-hora por semana<\/td>\n<\/tr>\n<tr>\n<td>Garanta del producto<\/td>\n<\/tr>\n<tr>\n<td>Un ao de servicio in situ, al siguiente da laborable<\/td>\n<\/tr>\n<tr>\n<td>Certificaciones del producto<\/td>\n<\/tr>\n<tr>\n<td>Energy star, blue angel ral-uz-171, ices-003 class a, bsmi class a, vcci class a, us fda\/cdrh, ul 60950-1, fcc class a, cul can\/csa-c22.2 60950-1, nom, met-i, iec 60825-1, cb en\/iec 60950-1, cb en\/iec 60825-1, ccd-035, ce doc en 62301 class a, en 62311, ce en\/iec 60950-1, ce en\/iec 60825-1, en 61000-3, en 55022 class a, eup, en 55024, ul, efta ce, cispr 22 class a, kcc, ccc, cecp, cel, a-tick doc, c-tick coc, ul-ar, kc mark, ul gs mark, iso 532b, ecma-370, ted, gost-r, sii, ter, bel giss<\/td>\n<\/tr>\n<tr>\n<td>Ciclo de trabajo mensual mximo<\/td>\n<\/tr>\n<tr>\n<td>Hasta 350000 pginas al mes3<\/td>\n<\/tr>\n<tr>\n<td>Volumen de pginas mensual recomendado<\/td>\n<\/tr>\n<tr>\n<td>5000 &#8211; 100000 pginas2<\/td>\n<\/tr>\n<tr>\n<td>Ambiente operativo especfico<\/td>\n<\/tr>\n<tr>\n<td>Humedad: 8 a 80 de humedad relativa<\/td>\n<\/tr>\n<tr>\n<td>Temperatura: 10 a 32\u00b0c<\/td>\n<\/tr>\n<tr>\n<td>Altitud: 0 &#8211; 2896 metros<\/td>\n<\/tr>\n<tr>\n<td>Licencia\/trminos del acuerdo<\/td>\n<\/tr>\n<tr>\n<td>Las impresoras se venden sujetas a ciertas condiciones de licencia \/ acuerdo. visita www.lexmark.com\/printerlicense para ms detalles.<\/td>\n<\/tr>\n<tr>\n<td>Pas de origen<\/td>\n<\/tr>\n<tr>\n<td>China prc<\/td>\n<\/tr>\n<tr>\n<td>Cdigo unspsc<\/td>\n<\/tr>\n<tr>\n<td>43212110<\/td>\n<\/tr>\n<tr>\n<td>Cdigo arancelario armonizado<\/td>\n<\/tr>\n<tr>\n<td>8443.31.0000<\/td>\n<\/tr>\n<tr>\n<td>1 este producto incluye software desarrollado por openssl project para su uso en openssl toolkit. http:\/\/www.openssl.org\/<\/td>\n<\/tr>\n<tr>\n<td>2el volumen de pgina mensual recomendado es un rango de pginas que ayuda a los clientes a evaluar las ofertas de productos de lexmark en funcin del nmero promedio de pginas que los clientes planean imprimir en el dispositivo cada mes. lexmark recomienda que el nmero de pginas por mes est dentro del rango establecido para un rendimiento ptimo del dispositivo, en funcin de factores que incluyen: intervalos de reemplazo de suministros, intervalos de carga de papel, velocidad y uso tpico del cliente.<\/td>\n<\/tr>\n<tr>\n<td>3el ciclo de trabajo mensual mximo se define como la cantidad mxima de pginas que un dispositivo puede entregar en un mes utilizando una operacin de mltiples escalas. esta mtrica proporciona una comparacin de robustez en relacin con otras impresoras y mfp de lexmark.<\/td>\n<\/tr>\n<tr>\n<td>4el rendimiento real puede variar en funcin de otros factores, como la velocidad del dispositivo, el tamao del papel y la orientacin de alimentacin, la cobertura del tner, la bandeja de origen del papel, el porcentaje de impresin solo en negro y la complejidad media de los trabajos de impresin.<\/td>\n<\/tr>\n<tr>\n<td>5 promedio del valor de rendimiento de pgina estndar declarado de acuerdo con iso \/ iec 19752.<\/td>\n<\/tr>\n<tr>\n<td>6velocidad de impresin y copia medidas de acuerdo con iso\/iec 24734 e iso\/iec 24735 respectivamente esat. para obtener ms informacin, consulte: www.lexmark.com\/isospeeds.<\/td>\n<\/tr>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Con una capacidad de salida de hasta 70 [66] ppm, componentes de imagen duraderos, capacidad de tner de ultra alto rendimiento, durabilidad excepcional, disco duro estndar y completas opciones de acabado, mx826ade es la impresora lder monocromtica para grupos de trabajo grandes de lexmark. Una pantalla tctil de alto nivel de 10 pulgadas con interfaz e-task lo mantiene informado y en control, ya sea si se conecta a travs de ethernet, usb u opciones simples de impresin mvil. La tecnologa de manejo de papel slido est diseada para que la impresin sea ms confiable, mientras que el tner de reemplazo de ultra alto rendimiento favorece el tiempo de funcionamiento y el diseo personalizado mejora la capacidad de mantenimiento. Adems, los productos monocromticos para grupos de trabajo grandes que ms ahorran energa de lexmark cuentan con certificacin epeat\u00ae gold y energy star\u00ae 2.0.<\/p>\n","protected":false},"featured_media":283217,"comment_status":"open","ping_status":"open","template":"","meta":[],"product_cat":[1780,1782],"product_tag":[1630],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>[ Lexmark ] &#129351; 25b0610 Multifuncional Mx826ade, Np , Ppm 70 Negro, Laser Monocromatico, Usb, Ethernet, Duplex<\/title>\n<meta name=\"description\" content=\"Compra 25b0610 Multifuncional Mx826ade, Np , Ppm 70 Negro, Laser Monocromatico, Usb, Ethernet, Duplex + Env\u00edo a domicilio + Pago seguro + Garant\u00eda\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[ Lexmark ] &#129351; 25b0610 Multifuncional Mx826ade, Np , Ppm 70 Negro, Laser Monocromatico, Usb, Ethernet, Duplex\" \/>\n<meta property=\"og:description\" content=\"Compra 25b0610 Multifuncional Mx826ade, Np , Ppm 70 Negro, Laser Monocromatico, Usb, Ethernet, Duplex + Env\u00edo a domicilio + Pago seguro + Garant\u00eda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/\" \/>\n<meta property=\"og:site_name\" content=\"Compuviper\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/compuviper\" \/>\n<meta property=\"og:image\" content=\"https:\/\/compuviper.mx\/tienda\/wp-content\/uploads\/2026\/06\/Multifuncional-lexmark-mx826ade-np-25b0610-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Precio\" \/>\n\t<meta name=\"twitter:data1\" content=\"&#36;68,232 con IVA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/\",\"url\":\"https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/\",\"name\":\"[ Lexmark ] &#129351; 25b0610 Multifuncional Mx826ade, Np , Ppm 70 Negro, Laser Monocromatico, Usb, Ethernet, Duplex\",\"isPartOf\":{\"@id\":\"https:\/\/compuviper.mx\/tienda\/#website\"},\"datePublished\":\"2026-07-15T07:59:30+00:00\",\"dateModified\":\"2026-07-15T07:59:30+00:00\",\"description\":\"Compra 25b0610 Multifuncional Mx826ade, Np , Ppm 70 Negro, Laser Monocromatico, Usb, Ethernet, Duplex + Env\u00edo a domicilio + Pago seguro + Garant\u00eda\",\"breadcrumb\":{\"@id\":\"https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/compuviper.mx\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\/\/compuviper.mx\/tienda\/productos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Multifuncionales\",\"item\":\"https:\/\/compuviper.mx\/tienda\/categoria-producto\/multifuncionales\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Laser Monocromatica\",\"item\":\"https:\/\/compuviper.mx\/tienda\/categoria-producto\/multifuncionales\/laser-monocromatica\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Lexmark 25b0610 Multifuncional Mx826ade, Np , Ppm 70 Negro, Laser Monocromatico, Usb, Ethernet, Duplex\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/compuviper.mx\/tienda\/#website\",\"url\":\"https:\/\/compuviper.mx\/tienda\/\",\"name\":\"Compuviper\",\"description\":\"Proveedor de Computadoras, Laptops, Servidores, Monitores, Puntos de Venta, Teclados,   Impresoras, T\u00f3ner, C\u00e1maras de Seguridad y m\u00e1s en tu tienda en l\u00ednea\",\"publisher\":{\"@id\":\"https:\/\/compuviper.mx\/tienda\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/compuviper.mx\/tienda\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/compuviper.mx\/tienda\/#organization\",\"name\":\"Compuviper\",\"url\":\"https:\/\/compuviper.mx\/tienda\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/compuviper.mx\/tienda\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/compuviper.mx\/tienda\/wp-content\/uploads\/2021\/08\/Logo-Compuviper-10.png\",\"contentUrl\":\"https:\/\/compuviper.mx\/tienda\/wp-content\/uploads\/2021\/08\/Logo-Compuviper-10.png\",\"width\":1000,\"height\":500,\"caption\":\"Compuviper\"},\"image\":{\"@id\":\"https:\/\/compuviper.mx\/tienda\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/compuviper\",\"https:\/\/www.youtube.com\/channel\/UCf73dERp9Y3cfOq7q8BhLjA?view_as=subscriber\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"LEXMARK\" \/>\n<meta property=\"product:price:amount\" content=\"68232\" \/>\n<meta property=\"product:price:currency\" content=\"MXN\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"25B0610\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[ Lexmark ] &#129351; 25b0610 Multifuncional Mx826ade, Np , Ppm 70 Negro, Laser Monocromatico, Usb, Ethernet, Duplex","description":"Compra 25b0610 Multifuncional Mx826ade, Np , Ppm 70 Negro, Laser Monocromatico, Usb, Ethernet, Duplex + Env\u00edo a domicilio + Pago seguro + Garant\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/","og_locale":"es_MX","og_type":"article","og_title":"[ Lexmark ] &#129351; 25b0610 Multifuncional Mx826ade, Np , Ppm 70 Negro, Laser Monocromatico, Usb, Ethernet, Duplex","og_description":"Compra 25b0610 Multifuncional Mx826ade, Np , Ppm 70 Negro, Laser Monocromatico, Usb, Ethernet, Duplex + Env\u00edo a domicilio + Pago seguro + Garant\u00eda","og_url":"https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/","og_site_name":"Compuviper","article_publisher":"https:\/\/www.facebook.com\/compuviper","og_image":[{"width":200,"height":200,"url":"https:\/\/compuviper.mx\/tienda\/wp-content\/uploads\/2026\/06\/Multifuncional-lexmark-mx826ade-np-25b0610-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Precio":"&#36;68,232 con IVA","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/","url":"https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/","name":"[ Lexmark ] &#129351; 25b0610 Multifuncional Mx826ade, Np , Ppm 70 Negro, Laser Monocromatico, Usb, Ethernet, Duplex","isPartOf":{"@id":"https:\/\/compuviper.mx\/tienda\/#website"},"datePublished":"2026-07-15T07:59:30+00:00","dateModified":"2026-07-15T07:59:30+00:00","description":"Compra 25b0610 Multifuncional Mx826ade, Np , Ppm 70 Negro, Laser Monocromatico, Usb, Ethernet, Duplex + Env\u00edo a domicilio + Pago seguro + Garant\u00eda","breadcrumb":{"@id":"https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/compuviper.mx\/tienda\/producto\/lexmark-25b0610-multifuncional-mx826ade-np-ppm-70-negro-laser-monocromatico-usb-ethernet-duplex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/compuviper.mx\/tienda\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/compuviper.mx\/tienda\/productos\/"},{"@type":"ListItem","position":3,"name":"Multifuncionales","item":"https:\/\/compuviper.mx\/tienda\/categoria-producto\/multifuncionales\/"},{"@type":"ListItem","position":4,"name":"Laser Monocromatica","item":"https:\/\/compuviper.mx\/tienda\/categoria-producto\/multifuncionales\/laser-monocromatica\/"},{"@type":"ListItem","position":5,"name":"Lexmark 25b0610 Multifuncional Mx826ade, Np , Ppm 70 Negro, Laser Monocromatico, Usb, Ethernet, Duplex"}]},{"@type":"WebSite","@id":"https:\/\/compuviper.mx\/tienda\/#website","url":"https:\/\/compuviper.mx\/tienda\/","name":"Compuviper","description":"Proveedor de Computadoras, Laptops, Servidores, Monitores, Puntos de Venta, Teclados,   Impresoras, T\u00f3ner, C\u00e1maras de Seguridad y m\u00e1s en tu tienda en l\u00ednea","publisher":{"@id":"https:\/\/compuviper.mx\/tienda\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/compuviper.mx\/tienda\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/compuviper.mx\/tienda\/#organization","name":"Compuviper","url":"https:\/\/compuviper.mx\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/compuviper.mx\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/compuviper.mx\/tienda\/wp-content\/uploads\/2021\/08\/Logo-Compuviper-10.png","contentUrl":"https:\/\/compuviper.mx\/tienda\/wp-content\/uploads\/2021\/08\/Logo-Compuviper-10.png","width":1000,"height":500,"caption":"Compuviper"},"image":{"@id":"https:\/\/compuviper.mx\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/compuviper","https:\/\/www.youtube.com\/channel\/UCf73dERp9Y3cfOq7q8BhLjA?view_as=subscriber"]}]},"product_brand":"LEXMARK","product_price_amount":"68232","product_price_currency":"MXN","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"25B0610","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/compuviper.mx\/tienda\/wp-json\/wp\/v2\/product\/283216"}],"collection":[{"href":"https:\/\/compuviper.mx\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/compuviper.mx\/tienda\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/compuviper.mx\/tienda\/wp-json\/wp\/v2\/comments?post=283216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/compuviper.mx\/tienda\/wp-json\/wp\/v2\/media\/283217"}],"wp:attachment":[{"href":"https:\/\/compuviper.mx\/tienda\/wp-json\/wp\/v2\/media?parent=283216"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/compuviper.mx\/tienda\/wp-json\/wp\/v2\/product_cat?post=283216"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/compuviper.mx\/tienda\/wp-json\/wp\/v2\/product_tag?post=283216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}